{"id":327,"count":14,"description":"","link":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/","name":"\u0426\u043e\u043a\u043e\u043b\u044c","slug":"soklid-ru","taxonomy":"kasutuskoht","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0426\u043e\u043a\u043e\u043b\u044c Archives | Eskaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0426\u043e\u043a\u043e\u043b\u044c Archives | Eskaro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/\" \/>\n<meta property=\"og:site_name\" content=\"Eskaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/primenenie\\\/soklid-ru\\\/\",\"url\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/primenenie\\\/soklid-ru\\\/\",\"name\":\"\u0426\u043e\u043a\u043e\u043b\u044c Archives | Eskaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/primenenie\\\/soklid-ru\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/primenenie\\\/soklid-ru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0426\u043e\u043a\u043e\u043b\u044c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/\",\"name\":\"Eskaro\",\"description\":\"Development\",\"publisher\":{\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/#organization\",\"name\":\"Eskaro AS\",\"url\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eskaro.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/eskaro-logo-main-svg-1.png\",\"contentUrl\":\"https:\\\/\\\/eskaro.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/eskaro-logo-main-svg-1.png\",\"width\":350,\"height\":284,\"caption\":\"Eskaro AS\"},\"image\":{\"@id\":\"https:\\\/\\\/eskaro.ee\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eskarovarvitehas\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCxPgDohdajei-gUTkWlk0ng\",\"https:\\\/\\\/www.instagram.com\\\/eskaro_estonia\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@eskaro_estonia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0426\u043e\u043a\u043e\u043b\u044c Archives | Eskaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0426\u043e\u043a\u043e\u043b\u044c Archives | Eskaro","og_url":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/","og_site_name":"Eskaro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/","url":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/","name":"\u0426\u043e\u043a\u043e\u043b\u044c Archives | Eskaro","isPartOf":{"@id":"https:\/\/eskaro.ee\/ru\/#website"},"breadcrumb":{"@id":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/#breadcrumb"},"inLanguage":"ru-RU"},{"@type":"BreadcrumbList","@id":"https:\/\/eskaro.ee\/ru\/primenenie\/soklid-ru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eskaro.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"\u0426\u043e\u043a\u043e\u043b\u044c"}]},{"@type":"WebSite","@id":"https:\/\/eskaro.ee\/ru\/#website","url":"https:\/\/eskaro.ee\/ru\/","name":"Eskaro","description":"Development","publisher":{"@id":"https:\/\/eskaro.ee\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eskaro.ee\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/eskaro.ee\/ru\/#organization","name":"Eskaro AS","url":"https:\/\/eskaro.ee\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/eskaro.ee\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/eskaro.ee\/wp-content\/uploads\/2024\/12\/eskaro-logo-main-svg-1.png","contentUrl":"https:\/\/eskaro.ee\/wp-content\/uploads\/2024\/12\/eskaro-logo-main-svg-1.png","width":350,"height":284,"caption":"Eskaro AS"},"image":{"@id":"https:\/\/eskaro.ee\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eskarovarvitehas","https:\/\/www.youtube.com\/channel\/UCxPgDohdajei-gUTkWlk0ng","https:\/\/www.instagram.com\/eskaro_estonia\/","https:\/\/www.tiktok.com\/@eskaro_estonia"]}]}},"_links":{"self":[{"href":"https:\/\/eskaro.ee\/ru\/wp-json\/wp\/v2\/kasutuskoht\/327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eskaro.ee\/ru\/wp-json\/wp\/v2\/kasutuskoht"}],"about":[{"href":"https:\/\/eskaro.ee\/ru\/wp-json\/wp\/v2\/taxonomies\/kasutuskoht"}],"wp:post_type":[{"href":"https:\/\/eskaro.ee\/ru\/wp-json\/wp\/v2\/product?kasutuskoht=327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}